{"id":92,"date":"2022-11-24T12:36:52","date_gmt":"2022-11-24T12:36:52","guid":{"rendered":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/?p=92"},"modified":"2022-11-24T12:36:54","modified_gmt":"2022-11-24T12:36:54","slug":"funil-de-conversao","status":"publish","type":"post","link":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/","title":{"rendered":"Funil de convers\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Do ponto de vista empresarial , uma boa estrat\u00e9gia de conte\u00fado \u00e9 aquela que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Representa bem o neg\u00f3cio<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Envolve potenciais consumidores de forma n\u00e3o intrusiva<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ajuda a aumentar as vendas ou atingir determinados objetivos que o neg\u00f3cio tem<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de come\u00e7ar a desenvolver uma estrat\u00e9gia de conte\u00fado e integr\u00e1-la aos processos de produ\u00e7\u00e3o de seu <a href=\"https:\/\/www.cria\u00e7\u00e3o-site-s\u00e3o-paulo-sp.com.br\/\">site<\/a> , \u00e9 crucial entender a jornada que seu cliente percorre desde o primeiro contato com sua empresa at\u00e9 a compra. Em termos gerais, podemos nos referir \u00e0 jornada que uma pessoa faz de n\u00e3o cliente para nosso cliente como o funil de convers\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um funil de convers\u00e3o generalizada pode ser composto de quatro etapas (emprestadas do setor de marketing):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conscientiza\u00e7\u00e3o: A fase do contato inicial com o cliente.<br>\u00c9 quando o cliente aprende pela primeira vez sobre sua empresa.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Interesse: Uma vez que o cliente conhece sua empresa, ele pode se interessar por voc\u00ea.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desejo: Depois que o interesse do cliente \u00e9 despertado, o cliente pode chegar a um ponto em que come\u00e7a a querer seus produtos e servi\u00e7os, embora nenhuma a\u00e7\u00e3o de compra tenha sido feita nesta fase.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A\u00e7\u00e3o: Nesta fase do funil de convers\u00e3o, o cliente n\u00e3o est\u00e1 apenas querendo e sonhando acordado com seu produto\/servi\u00e7o, mas tamb\u00e9m junta dinheiro, tempo e esfor\u00e7o necess\u00e1rios para compr\u00e1-lo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O acr\u00f4nimo AIDA nos ajuda a lembrar desses est\u00e1gios e \u00e9 emprestado do setor de marketing. O comportamento do cliente difere amplamente em todos esses est\u00e1gios. Algu\u00e9m que acabou de conhecer seu produto (conscientiza\u00e7\u00e3o), por exemplo, se comportar\u00e1 de forma diferente quando comparado a algu\u00e9m que j\u00e1 deseja comprar seu produto (a\u00e7\u00e3o).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo da estrat\u00e9gia de conte\u00fado \u00e9 levar os clientes de forma r\u00e1pida e eficaz da conscientiza\u00e7\u00e3o ao interesse, ao desejo \u00e0 a\u00e7\u00e3o, fornecendo o conte\u00fado certo para cada etapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concentre-se nas etapas mais importantes do funil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora voc\u00ea entende como os clientes passam do reconhecimento ao interesse, ao desejo \u00e0 a\u00e7\u00e3o, bem como que tipos de perguntas surgem durante a jornada do funil de convers\u00e3o. Desenvolver conte\u00fado para todas essas etapas \u00e9 muito trabalhoso, ent\u00e3o voc\u00ea precisa priorizar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 crucial entender quais etapas do funil de convers\u00e3o mais ajudariam voc\u00ea em um determinado momento. Por exemplo, se vemos apenas 10 visitantes por dia em nosso site, nosso problema \u00e9 a conscientiza\u00e7\u00e3o. Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em vez disso, poder\u00edamos come\u00e7ar com uma s\u00e9rie de postagens de blog sobre tend\u00eancias de design ou postagem de convidados em um blog de design l\u00edder para ajudar a criar conscientiza\u00e7\u00e3o. Como alternativa, se tivermos um n\u00edvel saud\u00e1vel de tr\u00e1fego no site, mas os clientes nos perguntarem constantemente como comprar nosso produto ou como configurar o teste gratuito, precisamos desenvolver conte\u00fado que aborde esses tipos de perguntas, talvez um webinar ou v\u00eddeo sobre usando o software, em vez de direcionar nossos recursos limitados na cria\u00e7\u00e3o de infogr\u00e1ficos virais e postagens de blog de convidados. Voc\u00ea pode estar se perguntando como determinar quais est\u00e1gios do funil s\u00e3o os mais importantes em um determinado momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o h\u00e1 uma resposta clara. No entanto, muitas vezes faz sentido ver onde est\u00e3o os gargalos. Voc\u00ea pode se fazer as seguintes perguntas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEu vejo muitos visitantes em nosso site?\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cOs clientes em potencial sabem sobre n\u00f3s?\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se n\u00e3o, precisamos trabalhar a conscientiza\u00e7\u00e3o.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cQuando fazemos guest post em outros sites, os clientes clicam no nosso site?\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cNossa empresa interessa a eles?\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEles se perguntam como isso funciona?\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se n\u00e3o, precisamos trabalhar com juros.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cOs clientes est\u00e3o interessados em comprar nosso produto?\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEles acreditam que \u00e9 um produto \u00f3timo e necess\u00e1rio?\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se n\u00e3o, precisamos trabalhar o desejo e provar os benef\u00edcios para os clientes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cAs pessoas entendem como e onde comprar nosso produto?\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cMinhas taxas de convers\u00e3o s\u00e3o semelhantes ou melhores que outras do setor?\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se n\u00e3o, talvez precisemos trabalhar em a\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do ponto de vista empresarial , uma boa estrat\u00e9gia de conte\u00fado \u00e9 aquela que: Antes de come\u00e7ar a desenvolver uma estrat\u00e9gia de conte\u00fado e integr\u00e1-la aos processos de produ\u00e7\u00e3o de seu site , \u00e9 crucial entender a jornada que seu cliente percorre desde o primeiro contato com sua empresa at\u00e9 a compra. Em termos gerais, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":93,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-92","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital","category-negocios","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funil de convers\u00e3o<\/title>\n<meta name=\"description\" content=\"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funil de convers\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T12:36:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-24T12:36:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/funil-de-conversao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/11cbed8a4fd6b0e8d3e54bcfb21df68d\"},\"headline\":\"Funil de convers\u00e3o\",\"datePublished\":\"2022-11-24T12:36:52+00:00\",\"dateModified\":\"2022-11-24T12:36:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\"},\"wordCount\":707,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization\"},\"articleSection\":[\"Marketing Digital\",\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\",\"url\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\",\"name\":\"Funil de convers\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#website\"},\"datePublished\":\"2022-11-24T12:36:52+00:00\",\"dateModified\":\"2022-11-24T12:36:54+00:00\",\"description\":\"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.\",\"breadcrumb\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funil de convers\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#website\",\"url\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/\",\"name\":\"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization\",\"name\":\"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o\",\"url\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/logo-projeto-web-criacao-de-sites.png\",\"contentUrl\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/logo-projeto-web-criacao-de-sites.png\",\"width\":450,\"height\":83,\"caption\":\"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o\"},\"image\":{\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/11cbed8a4fd6b0e8d3e54bcfb21df68d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d8fcd477bc639a384b3d61ce826dae80780041ebaefa5d67fdf68f70970fce3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d8fcd477bc639a384b3d61ce826dae80780041ebaefa5d67fdf68f70970fce3?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\"],\"url\":\"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/author\/servers_xottzoue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funil de convers\u00e3o","description":"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/","og_locale":"pt_BR","og_type":"article","og_title":"Funil de convers\u00e3o","og_description":"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.","og_url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/","og_site_name":"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o","article_published_time":"2022-11-24T12:36:52+00:00","article_modified_time":"2022-11-24T12:36:54+00:00","og_image":[{"width":1199,"height":686,"url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/funil-de-conversao.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#article","isPartOf":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/"},"author":{"name":"admin","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/11cbed8a4fd6b0e8d3e54bcfb21df68d"},"headline":"Funil de convers\u00e3o","datePublished":"2022-11-24T12:36:52+00:00","dateModified":"2022-11-24T12:36:54+00:00","mainEntityOfPage":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/"},"wordCount":707,"commentCount":0,"publisher":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization"},"articleSection":["Marketing Digital","Neg\u00f3cios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/","url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/","name":"Funil de convers\u00e3o","isPartOf":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#website"},"datePublished":"2022-11-24T12:36:52+00:00","dateModified":"2022-11-24T12:36:54+00:00","description":"Desenvolver um FAQ sobre como comprar e instalar nosso software n\u00e3o ajudar\u00e1 porque ningu\u00e9m est\u00e1 interessado e desejando nosso produto ainda.","breadcrumb":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/funil-de-conversao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/"},{"@type":"ListItem","position":2,"name":"Funil de convers\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#website","url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/","name":"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o","description":"","publisher":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#organization","name":"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o","url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/logo\/image\/","url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/logo-projeto-web-criacao-de-sites.png","contentUrl":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-content\/uploads\/2022\/11\/logo-projeto-web-criacao-de-sites.png","width":450,"height":83,"caption":"Ag\u00eancia de Cria\u00e7\u00e3o de Sites em Vinhedo SP, Or\u00e7amento e Pre\u00e7o"},"image":{"@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/11cbed8a4fd6b0e8d3e54bcfb21df68d","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7d8fcd477bc639a384b3d61ce826dae80780041ebaefa5d67fdf68f70970fce3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d8fcd477bc639a384b3d61ce826dae80780041ebaefa5d67fdf68f70970fce3?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo"],"url":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/author\/servers_xottzoue\/"}]}},"_links":{"self":[{"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":1,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/posts\/92\/revisions\/94"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siteprojetoweb.com.br\/marketing-de-conteudo\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}